{"id":8409,"date":"2017-05-04T11:49:10","date_gmt":"2017-05-04T09:49:10","guid":{"rendered":"http:\/\/cmpaix.eu\/fr\/?p=8409"},"modified":"2021-09-29T17:06:08","modified_gmt":"2021-09-29T15:06:08","slug":"venez-parler-europe-avec-le-journaliste-alex-taylor-au-centre-mondial-de-la-paix","status":"publish","type":"post","link":"http:\/\/cmpaix.eu\/fr\/venez-parler-europe-avec-le-journaliste-alex-taylor-au-centre-mondial-de-la-paix\/","title":{"rendered":"Venez parler Europe avec le journaliste Alex TAYLOR au Centre Mondial de la Paix"},"content":{"rendered":"<p><strong>Venez parler Europe avec le journaliste europ\u00e9en Alex TAYLOR le 9 mai 2017 \u00e0 15h au Centre Mondial de la Paix, des libert\u00e9s et des droits de l\u2019Homme<\/strong><\/p>\n<p><strong>A l\u2019occasion de la Journ\u00e9e de l\u2019Europe, le journaliste europ\u00e9en Alex TAYLOR animera un temps d\u2019\u00e9change sur les r\u00e9alit\u00e9s et les perspectives europ\u00e9ennes apr\u00e8s le BREXIT.<\/strong><\/p>\n<p><strong>Alors que le projet europ\u00e9en nourrit de nombreux d\u00e9bats publics en France et dans de nombreux \u00e9tats europ\u00e9ens<\/strong>, Alex TAYLOR partagera son exp\u00e9rience de journaliste europ\u00e9en en revenant sur les principaux enjeux de l\u2019Union europ\u00e9enne.<\/p>\n<p><strong>Brexit, manifestations pro europ\u00e9ennes en Hongrie, Europe au c\u0153ur des d\u00e9bats politiques fran\u00e7ais, relance de la construction europ\u00e9enne, d\u00e9fense europ\u00e9enne,<\/strong> \u2026 sont autant de sujets qui pourront \u00eatre abord\u00e9s durant les discussions.<\/p>\n<p><strong>Cette pr\u00e9sentation sera suivie d\u2019un d\u00e9bat avec le public.<\/strong><\/p>\n<p><img decoding=\"async\" src=\"http:\/\/cmpaix.eu\/fr\/wp-content\/uploads\/2017\/05\/taylor-europe.jpg\" data-orig-src=\"http:\/\/cmpaix.eu\/fr\/wp-content\/uploads\/2017\/05\/taylor-europe.jpg\" alt=\"\" width=\"510\" height=\"244\" class=\"lazyload aligncenter size-full wp-image-8410\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27510%27%20height%3D%27244%27%20viewBox%3D%270%200%20510%20244%27%3E%3Crect%20width%3D%27510%27%20height%3D%27244%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"http:\/\/cmpaix.eu\/fr\/wp-content\/uploads\/2017\/05\/taylor-europe-300x144.jpg 300w, http:\/\/cmpaix.eu\/fr\/wp-content\/uploads\/2017\/05\/taylor-europe.jpg 510w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 510px) 100vw, 510px\" \/><\/p>\n<p><em><strong>Alex Taylor est journaliste europ\u00e9en et animateur de radio et de t\u00e9l\u00e9vision<\/strong>. Tr\u00e8s connu en France apr\u00e8s avoir \u00e9t\u00e9 sur les ondes de France Inter <em>(T\u00e9lescopages, l&rsquo;Oreille en coin\u2026<\/em>), il a pr\u00e9sent\u00e9 et produit l&rsquo;\u00e9mission Continentales sur FR3 <em>(v\u00e9ritable compilation de journaux t\u00e9l\u00e9vis\u00e9s europ\u00e9ens diffus\u00e9s en version originale sous-titr\u00e9e)<\/em> ; puis a pr\u00e9sent\u00e9 l\u2019\u00e9mission CONFETTI sur ARTE avant de devenir directeur des programmes de Radio France internationale.<br \/>\n Il fonde en 1999, sa propre soci\u00e9t\u00e9 de production, Continental Connection, qui a produit notamment la s\u00e9rie Europuzzle, sur l&rsquo;identit\u00e9 nationale en Europe, prim\u00e9e aux Ith\u00e8mes 2001 <em>(meilleure \u00e9mission culturelle sur le net et satellite en France<\/em>). Alex Taylor a anim\u00e9, de 2000 \u00e0 2006, Vivre en Europe sur la Cha\u00eene parlementaire.<br \/>\nEnfin Alex TAYLOR assure la revue de presse europ\u00e9enne de France Inter depuis 30 ans.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Venez parler Europe avec le journaliste europ\u00e9en Alex TAYLOR le 9 mai 2017 \u00e0 15h au Centre Mondial de la Paix, des libert\u00e9s et des droits de l\u2019Homme A l\u2019occasion de la Journ\u00e9e de l\u2019Europe, le journaliste europ\u00e9en Alex TAYLOR animera un temps d\u2019\u00e9change sur les r\u00e9alit\u00e9s et les perspectives  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":8410,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[30],"tags":[],"class_list":["post-8409","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conferences"],"_links":{"self":[{"href":"http:\/\/cmpaix.eu\/fr\/wp-json\/wp\/v2\/posts\/8409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/cmpaix.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cmpaix.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cmpaix.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cmpaix.eu\/fr\/wp-json\/wp\/v2\/comments?post=8409"}],"version-history":[{"count":1,"href":"http:\/\/cmpaix.eu\/fr\/wp-json\/wp\/v2\/posts\/8409\/revisions"}],"predecessor-version":[{"id":8411,"href":"http:\/\/cmpaix.eu\/fr\/wp-json\/wp\/v2\/posts\/8409\/revisions\/8411"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cmpaix.eu\/fr\/wp-json\/wp\/v2\/media\/8410"}],"wp:attachment":[{"href":"http:\/\/cmpaix.eu\/fr\/wp-json\/wp\/v2\/media?parent=8409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cmpaix.eu\/fr\/wp-json\/wp\/v2\/categories?post=8409"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cmpaix.eu\/fr\/wp-json\/wp\/v2\/tags?post=8409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}